{"id":1073,"date":"2017-10-20T08:40:07","date_gmt":"2017-10-20T07:40:07","guid":{"rendered":"https:\/\/stuttgart-hypnobirthing.de\/blog\/?p=1073"},"modified":"2021-07-12T17:35:52","modified_gmt":"2021-07-12T16:35:52","slug":"der-fitnessball-fuer-schwangerschaft-und-geburt-richtig-gut","status":"publish","type":"post","link":"https:\/\/smartegeburt.de\/blog\/der-fitnessball-fuer-schwangerschaft-und-geburt-richtig-gut\/","title":{"rendered":"Der Fitnessball f\u00fcr Schwangerschaft und Geburt &#8211; richtig gut!"},"content":{"rendered":"\n\nDer liebe Fitnessball - wir kennen ihn alle. Als Kind haben wir freudig darauf herumgeh\u00fcpft (DER hatte nat\u00fcrlich zwei H\u00f6rnchen um sich daran festzuhalten), wir sehen sie manchmal in Fitnessstudios, Fitness-DVDs, und so weiter. Es geht um einen Fitnessball.\n\nDer Fitnessball ist normalerweise auch ein Angebot in Geburtsh\u00e4usern, Krankenh\u00e4usern, etc. Aber normalerweise macht er es nicht zu uns in unser Haus, wenn wir schwanger sind. Das ist sehr schade, und ich hoffe, dass euch dieser Blogeintrag <a href=\"https:\/\/smartegeburt.de\/blog\/der-fitnessball-fuer-schwangerschaft-und-geburt-richtig-gut\/\" class=\"more-link\">Weiterlesen [...]<\/a>","protected":false},"excerpt":{"rendered":"<p>Der liebe Fitnessball &#8211; wir kennen ihn alle. Als Kind haben wir freudig darauf herumgeh\u00fcpft (DER hatte nat\u00fcrlich zwei H\u00f6rnchen um sich daran festzuhalten), wir sehen sie manchmal in Fitnessstudios, Fitness-DVDs, und so weiter. Es geht um einen Fitnessball. Der Fitnessball ist normalerweise auch ein Angebot in Geburtsh\u00e4usern, Krankenh\u00e4usern, etc. Aber normalerweise macht er es nicht zu uns in unser Haus, wenn wir schwanger sind. Das ist sehr schade, und ich hoffe, dass euch dieser Blogeintrag Weiterlesen [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"kia_subtitle":"","footnotes":""},"categories":[51,56,44,5],"tags":[],"class_list":["post-1073","post","type-post","status-publish","format-standard","hentry","category-beckenbalance","category-bewegungen-fuer-geburtsfortschritt","category-studie","category-geburt"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Der liebe Fitnessball - wir kennen ihn alle. Als Kind haben wir freudig darauf herumgeh\u00fcpft (DER hatte nat\u00fcrlich zwei H\u00f6rnchen um sich daran festzuhalten), wir sehen sie manchmal in Fitnessstudios, Fitness-DVDs, und so weiter. Es geht um einen Fitnessball. Der Fitnessball ist normalerweise auch ein Angebot in Geburtsh\u00e4usern, Krankenh\u00e4usern, etc. Aber normalerweise macht er es\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"HypnoBirthing\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/smartegeburt.de\/blog\/der-fitnessball-fuer-schwangerschaft-und-geburt-richtig-gut\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Der Fitnessball f\u00fcr Schwangerschaft und Geburt \u2013 richtig gut! | Smarte Geburt Blog","description":"Der liebe Fitnessball - wir kennen ihn alle. Als Kind haben wir freudig darauf herumgeh\u00fcpft (DER hatte nat\u00fcrlich zwei H\u00f6rnchen um sich daran festzuhalten), wir sehen sie manchmal in Fitnessstudios, Fitness-DVDs, und so weiter. Es geht um einen Fitnessball. Der Fitnessball ist normalerweise auch ein Angebot in Geburtsh\u00e4usern, Krankenh\u00e4usern, etc. Aber normalerweise macht er es","canonical_url":"https:\/\/smartegeburt.de\/blog\/der-fitnessball-fuer-schwangerschaft-und-geburt-richtig-gut\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":null},"aioseo_meta_data":{"post_id":"1073","title":null,"description":null,"keywords":[],"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":{"locations":{"business":{"name":"","businessType":"","image":"","areaServed":"","urls":{"website":"","aboutPage":"","contactPage":""},"address":{"streetLine1":"","streetLine2":"","zipCode":"","city":"","state":"","country":"","addressFormat":"#streetLineOne\n#streetLineTwo\n#city, #state #zipCode"},"contact":{"email":"","phone":"","phoneFormatted":"","fax":"","faxFormatted":""},"ids":{"vat":"","tax":"","chamberOfCommerce":""},"payment":{"priceRange":"","currenciesAccepted":"","methods":""}}},"openingHours":{"useDefaults":true,"show":true,"alwaysOpen":false,"use24hFormat":false,"timezone":"","labels":{"closed":"","alwaysOpen":""},"days":{"monday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"tuesday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"wednesday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"thursday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"friday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"saturday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"},"sunday":{"open24h":false,"closed":false,"openTime":"09:00","closeTime":"17:00"}}}},"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-20 20:21:13","updated":"2025-06-04 09:09:10","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/smartegeburt.de\/blog\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/smartegeburt.de\/blog\/category\/schwangerschaft\/\" title=\"Schwangerschaft\">Schwangerschaft<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/smartegeburt.de\/blog\/category\/schwangerschaft\/geburtsvorbereitung\/\" title=\"Geburtsvorbereitung\">Geburtsvorbereitung<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/smartegeburt.de\/blog\/category\/schwangerschaft\/geburtsvorbereitung\/beckenbalance\/\" title=\"Beckenbalance\">Beckenbalance<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tDer Fitnessball f\u00fcr Schwangerschaft und Geburt \u2013 richtig gut!\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/smartegeburt.de\/blog"},{"label":"Schwangerschaft","link":"https:\/\/smartegeburt.de\/blog\/category\/schwangerschaft\/"},{"label":"Geburtsvorbereitung","link":"https:\/\/smartegeburt.de\/blog\/category\/schwangerschaft\/geburtsvorbereitung\/"},{"label":"Beckenbalance","link":"https:\/\/smartegeburt.de\/blog\/category\/schwangerschaft\/geburtsvorbereitung\/beckenbalance\/"},{"label":"Der Fitnessball f\u00fcr Schwangerschaft und Geburt &#8211; richtig gut!","link":"https:\/\/smartegeburt.de\/blog\/der-fitnessball-fuer-schwangerschaft-und-geburt-richtig-gut\/"}],"_links":{"self":[{"href":"https:\/\/smartegeburt.de\/blog\/wp-json\/wp\/v2\/posts\/1073","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smartegeburt.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smartegeburt.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smartegeburt.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smartegeburt.de\/blog\/wp-json\/wp\/v2\/comments?post=1073"}],"version-history":[{"count":1,"href":"https:\/\/smartegeburt.de\/blog\/wp-json\/wp\/v2\/posts\/1073\/revisions"}],"predecessor-version":[{"id":1999,"href":"https:\/\/smartegeburt.de\/blog\/wp-json\/wp\/v2\/posts\/1073\/revisions\/1999"}],"wp:attachment":[{"href":"https:\/\/smartegeburt.de\/blog\/wp-json\/wp\/v2\/media?parent=1073"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smartegeburt.de\/blog\/wp-json\/wp\/v2\/categories?post=1073"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smartegeburt.de\/blog\/wp-json\/wp\/v2\/tags?post=1073"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}