{"id":624,"date":"2017-03-14T20:35:33","date_gmt":"2017-03-14T19:35:33","guid":{"rendered":"https:\/\/stuttgart-hypnobirthing.de\/blog\/?p=624"},"modified":"2021-02-11T18:25:27","modified_gmt":"2021-02-11T17:25:27","slug":"herzlich-willkommen-mika-pedro-co","status":"publish","type":"post","link":"https:\/\/smartegeburt.de\/blog\/herzlich-willkommen-mika-pedro-co\/","title":{"rendered":"Herzlich Willkommen Mika Pedro :-)"},"content":{"rendered":"\nIm Krankenhaus N\u00fcrtingen\n\n\n\n\n\n\nEin neues Hypnobirthing-Baby hat im Krankenhaus N\u00fcrtingen das Licht der Welt erblickt! Die Mama hat mir ihren Geburtsbericht zukommen lassen, und mir fantastischerweise auch die Erlaubnis gegeben, ihn mit euch zu teilen! Das freut mich ungemein! Vielen Dank!\nLiebe S., ich finde es wirklich wundervoll wie toll Du Deine Geburt (innerlich) gestaltet hast. Schon in den letzten Wochen Deiner Schwangerschaft wurde Dir das Entspannen ja erschwert, da Dein medizinisches <a href=\"https:\/\/smartegeburt.de\/blog\/herzlich-willkommen-mika-pedro-co\/\" class=\"more-link\">Weiterlesen [...]<\/a>","protected":false},"excerpt":{"rendered":"<p>Im Krankenhaus N\u00fcrtingen Ein neues Hypnobirthing-Baby hat im Krankenhaus N\u00fcrtingen das Licht der Welt erblickt! Die Mama hat mir ihren Geburtsbericht zukommen lassen, und mir fantastischerweise auch die Erlaubnis gegeben, ihn mit euch zu teilen! Das freut mich ungemein! Vielen Dank! Liebe S., ich finde es wirklich wundervoll wie toll Du Deine Geburt (innerlich) gestaltet hast. Schon in den letzten Wochen Deiner Schwangerschaft wurde Dir das Entspannen ja erschwert, da Dein medizinisches Weiterlesen [&#8230;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"kia_subtitle":"","footnotes":""},"categories":[39,59,41,1,9],"tags":[],"class_list":["post-624","post","type-post","status-publish","format-standard","hentry","category-erfahrungsberichte","category-geburtsberichte-meiner-paare","category-hypnobirthing","category-uncategorized","category-visual"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Im Krankenhaus N\u00fcrtingen Ein neues Hypnobirthing-Baby hat im Krankenhaus N\u00fcrtingen das Licht der Welt erblickt! Die Mama hat mir ihren Geburtsbericht zukommen lassen, und mir fantastischerweise auch die Erlaubnis gegeben, ihn mit euch zu teilen! Das freut mich ungemein! Vielen Dank! Liebe S., ich finde es wirklich wundervoll wie toll Du Deine Geburt (innerlich) gestaltet\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"HypnoBirthing\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/smartegeburt.de\/blog\/herzlich-willkommen-mika-pedro-co\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Herzlich Willkommen Mika Pedro :-) | Smarte Geburt Blog","description":"Im Krankenhaus N\u00fcrtingen Ein neues Hypnobirthing-Baby hat im Krankenhaus N\u00fcrtingen das Licht der Welt erblickt! Die Mama hat mir ihren Geburtsbericht zukommen lassen, und mir fantastischerweise auch die Erlaubnis gegeben, ihn mit euch zu teilen! Das freut mich ungemein! Vielen Dank! Liebe S., ich finde es wirklich wundervoll wie toll Du Deine Geburt (innerlich) gestaltet","canonical_url":"https:\/\/smartegeburt.de\/blog\/herzlich-willkommen-mika-pedro-co\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":null},"aioseo_meta_data":{"post_id":"624","title":null,"description":null,"keywords":[],"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"none","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"},\"book\":[],\"event\":[],\"jobPosting\":[],\"music\":[],\"person\":[],\"restaurant\":[],\"service\":[],\"video\":[]}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":{"businessInfo":{"name":"","urls":{"website":"","aboutPage":"","contactPage":""},"address":{"line1":"","line2":"","zip":"","city":"","state":"","country":""},"contact":{"email":"","phone":"","fax":""},"ids":{"vatID":"","taxID":"","chamberID":""},"payment":{"priceIndication":"","currenciesAccepted":"","methodsAccepted":""},"areaServed":""},"openingHours":{"show":false,"closedLabel":"","open24h":false,"open24hLabel":"","open247":false,"use24hFormat":false,"twoSets":false,"timezone":"","hours":[]}},"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2021-01-20 20:23:44","updated":"2025-06-04 09:01:22","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/smartegeburt.de\/blog\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/smartegeburt.de\/blog\/category\/schwangerschaft\/\" title=\"Schwangerschaft\">Schwangerschaft<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/smartegeburt.de\/blog\/category\/schwangerschaft\/geburtsvorbereitung\/\" title=\"Geburtsvorbereitung\">Geburtsvorbereitung<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/smartegeburt.de\/blog\/category\/schwangerschaft\/geburtsvorbereitung\/hypnobirthing\/\" title=\"HypnoBirthing\">HypnoBirthing<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tHerzlich Willkommen Mika Pedro :-)\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/smartegeburt.de\/blog"},{"label":"Schwangerschaft","link":"https:\/\/smartegeburt.de\/blog\/category\/schwangerschaft\/"},{"label":"Geburtsvorbereitung","link":"https:\/\/smartegeburt.de\/blog\/category\/schwangerschaft\/geburtsvorbereitung\/"},{"label":"HypnoBirthing","link":"https:\/\/smartegeburt.de\/blog\/category\/schwangerschaft\/geburtsvorbereitung\/hypnobirthing\/"},{"label":"Herzlich Willkommen Mika Pedro :-)","link":"https:\/\/smartegeburt.de\/blog\/herzlich-willkommen-mika-pedro-co\/"}],"_links":{"self":[{"href":"https:\/\/smartegeburt.de\/blog\/wp-json\/wp\/v2\/posts\/624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/smartegeburt.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/smartegeburt.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/smartegeburt.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/smartegeburt.de\/blog\/wp-json\/wp\/v2\/comments?post=624"}],"version-history":[{"count":0,"href":"https:\/\/smartegeburt.de\/blog\/wp-json\/wp\/v2\/posts\/624\/revisions"}],"wp:attachment":[{"href":"https:\/\/smartegeburt.de\/blog\/wp-json\/wp\/v2\/media?parent=624"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/smartegeburt.de\/blog\/wp-json\/wp\/v2\/categories?post=624"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/smartegeburt.de\/blog\/wp-json\/wp\/v2\/tags?post=624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}